{"id":1097,"count":1,"description":"","link":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/","name":"Monkey King: hero is Back","slug":"monkey-king-hero-is-back","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Monkey King: hero is Back - Green Man Gaming Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monkey King: hero is Back - Green Man Gaming Blog\" \/>\n<meta property=\"og:url\" content=\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/\" \/>\n<meta property=\"og:site_name\" content=\"Green Man Gaming Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GreenManGaming\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/\",\"url\":\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/\",\"name\":\"Monkey King: hero is Back - Green Man Gaming Blog\",\"isPartOf\":{\"@id\":\"http:\/\/10.0.116.4:80\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/10.0.116.4:80\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Monkey King: hero is Back\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/10.0.116.4:80\/#website\",\"url\":\"http:\/\/10.0.116.4:80\/\",\"name\":\"Green Man Gaming Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/10.0.116.4:80\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/10.0.116.4:80\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/10.0.116.4:80\/#organization\",\"name\":\"Green Man Gaming Blog\",\"url\":\"http:\/\/10.0.116.4:80\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/10.0.116.4:80\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/10.0.116.4:80\/wp-content\/uploads\/2025\/07\/f68c31ad99984f9ab6f525170a1ce0df.svg\",\"contentUrl\":\"http:\/\/10.0.116.4:80\/wp-content\/uploads\/2025\/07\/f68c31ad99984f9ab6f525170a1ce0df.svg\",\"width\":1,\"height\":1,\"caption\":\"Green Man Gaming Blog\"},\"image\":{\"@id\":\"http:\/\/10.0.116.4:80\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GreenManGaming\",\"https:\/\/x.com\/GreenManGaming\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monkey King: hero is Back - Green Man Gaming Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/","og_locale":"en_US","og_type":"article","og_title":"Monkey King: hero is Back - Green Man Gaming Blog","og_url":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/","og_site_name":"Green Man Gaming Blog","twitter_card":"summary_large_image","twitter_site":"@GreenManGaming","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/","url":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/","name":"Monkey King: hero is Back - Green Man Gaming Blog","isPartOf":{"@id":"http:\/\/10.0.116.4:80\/#website"},"breadcrumb":{"@id":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/tag\/monkey-king-hero-is-back\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/10.0.116.4:80\/"},{"@type":"ListItem","position":2,"name":"Monkey King: hero is Back"}]},{"@type":"WebSite","@id":"http:\/\/10.0.116.4:80\/#website","url":"http:\/\/10.0.116.4:80\/","name":"Green Man Gaming Blog","description":"","publisher":{"@id":"http:\/\/10.0.116.4:80\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/10.0.116.4:80\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/10.0.116.4:80\/#organization","name":"Green Man Gaming Blog","url":"http:\/\/10.0.116.4:80\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/10.0.116.4:80\/#\/schema\/logo\/image\/","url":"http:\/\/10.0.116.4:80\/wp-content\/uploads\/2025\/07\/f68c31ad99984f9ab6f525170a1ce0df.svg","contentUrl":"http:\/\/10.0.116.4:80\/wp-content\/uploads\/2025\/07\/f68c31ad99984f9ab6f525170a1ce0df.svg","width":1,"height":1,"caption":"Green Man Gaming Blog"},"image":{"@id":"http:\/\/10.0.116.4:80\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GreenManGaming","https:\/\/x.com\/GreenManGaming"]}]}},"_links":{"self":[{"href":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/wp-json\/wp\/v2\/tags\/1097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/vpce-0921aaf1c67156043-4t1vg0wq.vpce-svc-0cf8d5d00172470c2.us-east-1.vpce.amazonaws.com\/wp-json\/wp\/v2\/posts?tags=1097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}